{"id":91,"count":7,"description":"","link":"https:\/\/demo.directorist.com\/theme\/dclassified\/category\/property\/","name":"Property","slug":"property","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/demo.directorist.com\/theme\/dclassified\/wp-json\/wp\/v2\/categories\/91","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.directorist.com\/theme\/dclassified\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/demo.directorist.com\/theme\/dclassified\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/demo.directorist.com\/theme\/dclassified\/wp-json\/wp\/v2\/posts?categories=91"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}