{"id":1718,"date":"2022-02-15T05:05:19","date_gmt":"2022-02-15T05:05:19","guid":{"rendered":"http:\/\/demo.directorist.com\/theme\/dclassified\/wp-content\/uploads\/2022\/02\/2.png"},"modified":"2022-02-15T05:05:19","modified_gmt":"2022-02-15T05:05:19","slug":"2","status":"inherit","type":"attachment","link":"https:\/\/demo.directorist.com\/theme\/dclassified\/2\/","title":{"rendered":"2"},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-1718","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/demo.directorist.com\/theme\/dclassified\/wp-content\/uploads\/2022\/02\/2.png'><img decoding=\"async\" width=\"102\" height=\"106\" src=\"https:\/\/demo.directorist.com\/theme\/dclassified\/wp-content\/uploads\/2022\/02\/2.png\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":102,"height":106,"file":"2022\/02\/2.png","sizes":{"wpwaxtheme-size3":{"file":"2-60x60.png","width":60,"height":60,"mime_type":"image\/png","source_url":"https:\/\/demo.directorist.com\/theme\/dclassified\/wp-content\/uploads\/2022\/02\/2-60x60.png"},"full":{"file":"2.png","width":102,"height":106,"mime_type":"image\/png","source_url":"https:\/\/demo.directorist.com\/theme\/dclassified\/wp-content\/uploads\/2022\/02\/2.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/demo.directorist.com\/theme\/dclassified\/wp-content\/uploads\/2022\/02\/2.png","filename":"2.png","filesize":2259,"_links":{"self":[{"href":"https:\/\/demo.directorist.com\/theme\/dclassified\/wp-json\/wp\/v2\/media\/1718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.directorist.com\/theme\/dclassified\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/demo.directorist.com\/theme\/dclassified\/wp-json\/wp\/v2\/types\/attachment"}],"replies":[{"embeddable":true,"href":"https:\/\/demo.directorist.com\/theme\/dclassified\/wp-json\/wp\/v2\/comments?post=1718"}]}}