{"id":35,"count":10,"description":"","link":"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/category\/international\/","name":"International","slug":"international","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/wp-json\/wp\/v2\/categories\/35","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/wp-json\/wp\/v2\/posts?categories=35"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}