{"id":1030,"date":"2021-10-04T02:41:07","date_gmt":"2021-10-04T02:41:07","guid":{"rendered":"http:\/\/demo.directorist.com\/theme\/onelisting-pro\/?page_id=1030"},"modified":"2021-11-10T06:55:10","modified_gmt":"2021-11-10T06:55:10","slug":"listing-categories","status":"publish","type":"page","link":"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/elements\/listing-categories\/","title":{"rendered":"Listing Categories"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1030\" class=\"elementor elementor-1030\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e48cfbb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e48cfbb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bfa3335\" data-id=\"bfa3335\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-91af6b5 elementor-widget elementor-widget-wpwaxtheme-all-categories\" data-id=\"91af6b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpwaxtheme-all-categories.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<div id=\"directorist\" class=\"atbd_wrapper directorist-w-100\">\r\n\r\n\t<div class=\"directorist-container-fluid\">\r\n\r\n\t\t<div class=\"directorist-categories\">\r\n\t\t\t\r\n\t\t\t<div class=\"directorist-row\">\r\n\t\t\t\r\n\t\t\t\t\n\t\t\t\t\t\t<div class=\"directorist-col-3\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<style>\n\t\t\t\t\t\t\t\t\t#directorist .onelisting-category-color-101,\n\t\t\t\t\t\t\t\t\t#directorist .onelisting-category-color-101 i:not(.directorist-icon-mask) {\n\t\t\t\t\t\t\t\t\t\tcolor: #cb3b3b !important;\n\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\t\t#directorist .onelisting-category-color-101 .directorist-icon-mask:after {\n\t\t\t\t\t\t\t\t\t\tbackground-color: #cb3b3b !important;\n\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\t<\/style>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<a class=\"directorist-categories__single\" href=\"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/single-category\/place\/?directory_type=general\">\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<figure>\r\n\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/wp-content\/uploads\/2025\/07\/NoPath-Copy-31@2x-1-1-476x340-1.png\" title=\"Place\" alt=\"Place\">\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/figure>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"cat-box\">\r\n\r\n\t\t\t\t\t\t\t\t\t<div class=\"cat-box__top\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"icon onelisting-category-color-101\"><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/demo.directorist.com\/theme\/onelisting-pro\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/map-marked-solid.svg)\"><\/i><\/div>\n\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"cat-info\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"cat-name\">Place<\/h4>\r\n\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"cat-box__bottom\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"cat-count\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<span class='directorist-category-count'>2<\/span> <span>listings<\/span>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t<\/a>\r\n\r\n\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"directorist-col-3\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<style>\n\t\t\t\t\t\t\t\t\t#directorist .onelisting-category-color-99,\n\t\t\t\t\t\t\t\t\t#directorist .onelisting-category-color-99 i:not(.directorist-icon-mask) {\n\t\t\t\t\t\t\t\t\t\tcolor: #17b978 !important;\n\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\t\t#directorist .onelisting-category-color-99 .directorist-icon-mask:after {\n\t\t\t\t\t\t\t\t\t\tbackground-color: #17b978 !important;\n\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\t<\/style>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<a class=\"directorist-categories__single\" href=\"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/single-category\/outdoor-activities\/?directory_type=general\">\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<figure>\r\n\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/wp-content\/uploads\/2025\/07\/slide-5-476x340-1.png\" title=\"Outdoor Activities\" alt=\"Outdoor Activities\">\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/figure>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"cat-box\">\r\n\r\n\t\t\t\t\t\t\t\t\t<div class=\"cat-box__top\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"icon onelisting-category-color-99\"><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/demo.directorist.com\/theme\/onelisting-pro\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/snowboarding-solid.svg)\"><\/i><\/div>\n\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"cat-info\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"cat-name\">Outdoor Activities<\/h4>\r\n\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"cat-box__bottom\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"cat-count\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<span class='directorist-category-count'>4<\/span> <span>listings<\/span>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t<\/a>\r\n\r\n\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"directorist-col-3\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<style>\n\t\t\t\t\t\t\t\t\t#directorist .onelisting-category-color-97,\n\t\t\t\t\t\t\t\t\t#directorist .onelisting-category-color-97 i:not(.directorist-icon-mask) {\n\t\t\t\t\t\t\t\t\t\tcolor: #9c1de7 !important;\n\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\t\t#directorist .onelisting-category-color-97 .directorist-icon-mask:after {\n\t\t\t\t\t\t\t\t\t\tbackground-color: #9c1de7 !important;\n\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\t<\/style>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<a class=\"directorist-categories__single\" href=\"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/single-category\/homes\/?directory_type=general\">\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<figure>\r\n\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/wp-content\/uploads\/2025\/07\/3-476x340.jpg\" title=\"Homes\" alt=\"Homes\">\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/figure>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"cat-box\">\r\n\r\n\t\t\t\t\t\t\t\t\t<div class=\"cat-box__top\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"icon onelisting-category-color-97\"><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/demo.directorist.com\/theme\/onelisting-pro\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/home-solid.svg)\"><\/i><\/div>\n\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"cat-info\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"cat-name\">Homes<\/h4>\r\n\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"cat-box__bottom\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"cat-count\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<span class='directorist-category-count'>1<\/span> <span>listing<\/span>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t<\/a>\r\n\r\n\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"directorist-col-3\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<style>\n\t\t\t\t\t\t\t\t\t#directorist .onelisting-category-color-96,\n\t\t\t\t\t\t\t\t\t#directorist .onelisting-category-color-96 i:not(.directorist-icon-mask) {\n\t\t\t\t\t\t\t\t\t\tcolor: #0b8457 !important;\n\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\t\t#directorist .onelisting-category-color-96 .directorist-icon-mask:after {\n\t\t\t\t\t\t\t\t\t\tbackground-color: #0b8457 !important;\n\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\t<\/style>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<a class=\"directorist-categories__single\" href=\"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/single-category\/shopping\/?directory_type=general\">\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<figure>\r\n\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/wp-content\/uploads\/2021\/09\/Blog-14-476x340.jpg\" title=\"Shopping\" alt=\"Shopping\">\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/figure>\r\n\r\n\t\t\t\t\t\t\t\t<div class=\"cat-box\">\r\n\r\n\t\t\t\t\t\t\t\t\t<div class=\"cat-box__top\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"icon onelisting-category-color-96\"><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/demo.directorist.com\/theme\/onelisting-pro\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/store-alt-solid.svg)\"><\/i><\/div>\n\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"cat-info\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"cat-name\">Shopping<\/h4>\r\n\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"cat-box__bottom\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"cat-count\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t<span class='directorist-category-count'>1<\/span> <span>listing<\/span>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\r\n\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t<\/a>\r\n\r\n\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t<\/div>\r\n\r\n\t\t<\/div>\r\n\r\n\t<\/div>\r\n\r\n<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Salon 3 listings Food 3 listings Place 5 listings Gym &amp; Fitness 3 listings Outdoor Activities 3 listings Automotive 3 listings Homes 3 listings Shopping 2 listings<\/p>\n","protected":false},"author":47,"featured_media":0,"parent":1010,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1030","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/wp-json\/wp\/v2\/pages\/1030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/wp-json\/wp\/v2\/comments?post=1030"}],"version-history":[{"count":0,"href":"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/wp-json\/wp\/v2\/pages\/1030\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/wp-json\/wp\/v2\/pages\/1010"}],"wp:attachment":[{"href":"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/wp-json\/wp\/v2\/media?parent=1030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}