{"id":29,"date":"2021-09-07T10:57:34","date_gmt":"2021-09-07T10:57:34","guid":{"rendered":"http:\/\/demo.directorist.com\/theme\/onelisting-pro\/privacy-policy-2\/"},"modified":"2021-09-07T10:57:34","modified_gmt":"2021-09-07T10:57:34","slug":"privacy-policy-2","status":"publish","type":"page","link":"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/privacy-policy-2\/","title":{"rendered":"Privacy Policy"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":47,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-29","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/wp-json\/wp\/v2\/pages\/29","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/wp-json\/wp\/v2\/comments?post=29"}],"version-history":[{"count":0,"href":"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/wp-json\/wp\/v2\/pages\/29\/revisions"}],"wp:attachment":[{"href":"https:\/\/demo.directorist.com\/theme\/onelisting-pro\/wp-json\/wp\/v2\/media?parent=29"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}